{"id":71,"count":3,"description":"","link":"https:\/\/mimex-auto-export.com\/index.php\/tag\/l3h2\/","name":"L3H2","slug":"l3h2","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mimex-auto-export.com\/index.php\/tag\/l3h2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/71\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mimex-auto-export.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/index.php\\\/tag\\\/l3h2\\\/#listItem\",\"name\":\"L3H2\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/index.php\\\/tag\\\/l3h2\\\/#listItem\",\"position\":2,\"name\":\"L3H2\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/71\\\/#collectionpage\",\"url\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/71\\\/\",\"name\":\"L3H2 - MIMEX AUTO\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/71\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/#organization\",\"name\":\"mimex-auto-export.com\",\"description\":\"Vente de v\\u00e9hicules neufs pour l'exportation depuis plus de 30 ans.\",\"url\":\"https:\\\/\\\/mimex-auto-export.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-Mimex-1.jpg\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/71\\\/#organizationLogo\",\"width\":200,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/71\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MIMEXAUTO\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@mimex.automobile?lang=fr\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/#website\",\"url\":\"https:\\\/\\\/mimex-auto-export.com\\\/\",\"name\":\"mimex-auto-export.com\",\"description\":\"Vente de v\\u00e9hicules neufs pour l'exportation depuis plus de 30 ans.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/mimex-auto-export.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"L3H2 - MIMEX AUTO","description":"","canonical_url":"https:\/\/mimex-auto-export.com\/index.php\/tag\/l3h2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mimex-auto-export.com\/wp-json\/wp\/v2\/tags\/71\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mimex-auto-export.com#listItem","position":1,"name":"Home","item":"https:\/\/mimex-auto-export.com","nextItem":{"@type":"ListItem","@id":"https:\/\/mimex-auto-export.com\/index.php\/tag\/l3h2\/#listItem","name":"L3H2"}},{"@type":"ListItem","@id":"https:\/\/mimex-auto-export.com\/index.php\/tag\/l3h2\/#listItem","position":2,"name":"L3H2","previousItem":{"@type":"ListItem","@id":"https:\/\/mimex-auto-export.com#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/mimex-auto-export.com\/wp-json\/wp\/v2\/tags\/71\/#collectionpage","url":"https:\/\/mimex-auto-export.com\/wp-json\/wp\/v2\/tags\/71\/","name":"L3H2 - MIMEX AUTO","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/mimex-auto-export.com\/#website"},"breadcrumb":{"@id":"https:\/\/mimex-auto-export.com\/wp-json\/wp\/v2\/tags\/71\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/mimex-auto-export.com\/#organization","name":"mimex-auto-export.com","description":"Vente de v\u00e9hicules neufs pour l'exportation depuis plus de 30 ans.","url":"https:\/\/mimex-auto-export.com\/","logo":{"@type":"ImageObject","url":"https:\/\/mimex-auto-export.com\/wp-content\/uploads\/2024\/01\/cropped-Mimex-1.jpg","@id":"https:\/\/mimex-auto-export.com\/wp-json\/wp\/v2\/tags\/71\/#organizationLogo","width":200,"height":100},"image":{"@id":"https:\/\/mimex-auto-export.com\/wp-json\/wp\/v2\/tags\/71\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/MIMEXAUTO\/","https:\/\/www.tiktok.com\/@mimex.automobile?lang=fr"]},{"@type":"WebSite","@id":"https:\/\/mimex-auto-export.com\/#website","url":"https:\/\/mimex-auto-export.com\/","name":"mimex-auto-export.com","description":"Vente de v\u00e9hicules neufs pour l'exportation depuis plus de 30 ans.","inLanguage":"en-US","publisher":{"@id":"https:\/\/mimex-auto-export.com\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mimex-auto-export.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tL3H2\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mimex-auto-export.com"},{"label":"L3H2","link":"https:\/\/mimex-auto-export.com\/index.php\/tag\/l3h2\/"}],"_links":{"self":[{"href":"https:\/\/mimex-auto-export.com\/index.php\/wp-json\/wp\/v2\/tags\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mimex-auto-export.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mimex-auto-export.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mimex-auto-export.com\/index.php\/wp-json\/wp\/v2\/posts?tags=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}